{"id":1006,"date":"2018-05-20T20:55:05","date_gmt":"2018-05-20T23:55:05","guid":{"rendered":"https:\/\/www.sistemizecoach.com\/blog\/?p=1006"},"modified":"2018-05-20T20:55:05","modified_gmt":"2018-05-20T23:55:05","slug":"como-aumentar-a-inteligencia-emocional-dos-coachees-com-coaching","status":"publish","type":"post","link":"https:\/\/www.sistemizecoach.com\/blog\/como-aumentar-a-inteligencia-emocional-dos-coachees-com-coaching\/","title":{"rendered":"Como aumentar a intelig\u00eancia emocional dos coachees com coaching"},"content":{"rendered":"<p>Para alcan\u00e7ar o sucesso em qualquer \u00e1rea da vida \u00e9 preciso desenvolver diversas habilidades como determina\u00e7\u00e3o, motiva\u00e7\u00e3o, resili\u00eancia, din\u00e2mica, comunica\u00e7\u00e3o assertiva e, claro, intelig\u00eancia emocional.<\/p>\n<p>Ser inteligente emocionalmente significa saber identificar, interpretar e gerenciar suas emo\u00e7\u00f5es de forma a reduzir o estresse, melhorar relacionamentos, estabelecer empatia e resolver problemas.<\/p>\n<p>Dispor dessas caracter\u00edsticas \u00e9 de grande valia em qualquer momento da vida e como ferramenta de mudan\u00e7a para qualquer objetivo. Por isso, trabalhar a intelig\u00eancia emocional deve ser tarefa indispens\u00e1vel em um processo de coaching.<\/p>\n<p>Neste artigo voc\u00ea conhecer\u00e1 alguns aspectos fundamentais da intelig\u00eancia emocional e como ela pode ser aprimorada pelo coach durante as suas sess\u00f5es com os seus coachees.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1009\" src=\"https:\/\/d1shiq7gsx6caf.cloudfront.net\/2018\/05\/inteligencia-emocional.jpg\" alt=\"\" width=\"740\" height=\"383\" srcset=\"https:\/\/d1shiq7gsx6caf.cloudfront.net\/2018\/05\/inteligencia-emocional.jpg 740w, https:\/\/d1shiq7gsx6caf.cloudfront.net\/2018\/05\/inteligencia-emocional-300x155.jpg 300w, https:\/\/d1shiq7gsx6caf.cloudfront.net\/2018\/05\/inteligencia-emocional-400x207.jpg 400w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<h2>Atributos da intelig\u00eancia emocional<\/h2>\n<p>Para que haja uma otimiza\u00e7\u00e3o da intelig\u00eancia emocional durante um processo de coaching, \u00e9 importante que tanto o coach quanto o seu coachee entendam quais s\u00e3o os atributos principais que tornam o gerenciamento das emo\u00e7\u00f5es mais efetivo.<\/p>\n<p>Podemos citar como atributos essenciais da intelig\u00eancia emocional:<\/p>\n<h3>Autoconhecimento<\/h3>\n<p>\u00c9 o reconhecer e interpretar corretamente seus <a href=\"https:\/\/www.sistemizecoach.com\/blog\/como-compreender-seus-pontos-fortes-e-fracos-com-o-coaching\/\">pontos fortes e pontos fracos<\/a>, suas rela\u00e7\u00f5es com o aspecto emocional e tamb\u00e9m como essas caracter\u00edsticas influenciam pessoas ou situa\u00e7\u00f5es ou sofrem influ\u00eancias de fatores externos.<\/p>\n<h3>Autocontrole<\/h3>\n<p>O autocontrole \u00e9 a capacidade de se manter est\u00e1vel ou de se adaptar em situa\u00e7\u00f5es de flutua\u00e7\u00f5es emocionais e nas ocasi\u00f5es de sentimentos intensos aflorados, como raiva, medo, surpresa e paix\u00e3o.<\/p>\n<h3>Consci\u00eancia social<\/h3>\n<p>\u00c9 a qualidade de quem capta as emo\u00e7\u00f5es das outras pessoas e tem a sensibilidade para compreender as circunst\u00e2ncias ao seu redor. Ter consci\u00eancia social \u00e9 tamb\u00e9m se sentir confort\u00e1vel e parte de um todo na sociedade.<\/p>\n<h3>Gest\u00e3o de relacionamento<\/h3>\n<p>Gerenciar rela\u00e7\u00f5es interpessoais \u00e9 saber como se comunicar da melhor forma poss\u00edvel com cada pessoa e em cada situa\u00e7\u00e3o diferente. Influenciar positivamente e interagir em rela\u00e7\u00f5es ben\u00e9ficas para todos os envolvidos tamb\u00e9m faz parte da gest\u00e3o de relacionamento.<\/p>\n<h2>Como aumentar a intelig\u00eancia emocional do coachee<\/h2>\n<p>A intelig\u00eancia emocional como um todo pode ser aprendida ou aprimorada por qualquer pessoa. Todos n\u00f3s possu\u00edmos uma forte carga emocional produzida por experi\u00eancias, pelo meio em que vivemos e tamb\u00e9m pela nossa <a href=\"https:\/\/www.sistemizecoach.com\/blog\/a-importancia-do-assessment-em-um-processo-de-coaching\/\">personalidade<\/a>. Podemos aprender a gerenciar essas emo\u00e7\u00f5es com <a href=\"https:\/\/www.sistemizecoach.com\/blog\/ferramentas-de-coaching\/\">ferramentas de coaching<\/a> focadas no <a href=\"https:\/\/www.sistemizecoach.com\/blog\/tecnicas-e-ferramentas-de-coaching-para-melhorar-o-autoconhecimento\/\">autoconhecimento<\/a> e na resolu\u00e7\u00e3o de problemas.<\/p>\n<p>Durante o processo de coaching, o coach pode ajudar o seu cliente a olhar para si mesmo buscando elementos que o tornar\u00e3o mais inteligente emocionalmente, facilitando a redu\u00e7\u00e3o das ang\u00fastias, do estresse, da ansiedade e dos conflitos intra e interpessoais.<\/p>\n<p>O coach pode, tamb\u00e9m, criar ou adaptar ferramentas de coaching com foco na intelig\u00eancia emocional do seu coachee, usando alguns aspectos como redu\u00e7\u00e3o do estresse, despertar da consci\u00eancia emocional, aprimoramento da comunica\u00e7\u00e3o e resolu\u00e7\u00e3o de conflitos.<\/p>\n<h3>Reduzindo o estresse di\u00e1rio<\/h3>\n<p>Altos n\u00edveis de estresse sobrecarregam a mente e diminuem o discernimento e a tranquilidade para interpretar situa\u00e7\u00f5es e resolver conflitos entre pessoas.<\/p>\n<p>Para ajudar o coachee a combater o seu estresse diariamente, \u00e9 preciso que sejam trabalhadas as seguintes quest\u00f5es:<\/p>\n<ul>\n<li>Quais s\u00e3o as situa\u00e7\u00f5es que mais fazem estressar?<\/li>\n<li>Quais s\u00e3o suas as rea\u00e7\u00f5es perante ao estresse?<\/li>\n<li>Como o seu corpo reage no momento da situa\u00e7\u00e3o estressante?<\/li>\n<li>Quem deixa voc\u00ea estressado? Por qu\u00ea?<\/li>\n<li>Como voc\u00ea se sente mais relaxado?<\/li>\n<li>O que pode fazer para reduzir o seu estresse di\u00e1rio?<\/li>\n<\/ul>\n<h3>Despertando a consci\u00eancia emocional<\/h3>\n<p>Ter consci\u00eancia total do estado emocional em que se encontra e quais s\u00e3o as suas consequ\u00eancias \u00e9 fundamental para o gerenciamento da intelig\u00eancia emocional.<\/p>\n<p>Para que esse aspecto seja desenvolvido, \u00e9 importante que o coach investigue junto com o seu coachee as seguintes quest\u00f5es:<\/p>\n<ul>\n<li>Suas emo\u00e7\u00f5es mais fortes despertam suas mem\u00f3rias passadas?<\/li>\n<li>Como voc\u00ea se sente emocionalmente no momento?<\/li>\n<li>Seus sentimentos s\u00e3o est\u00e1veis ou se alternam com facilidade?<\/li>\n<li>Voc\u00ea tem dificuldades em entender a si mesmo?<\/li>\n<li>Voc\u00ea consegue controlar suas emo\u00e7\u00f5es ou elas controlam voc\u00ea?<\/li>\n<li>Quais s\u00e3o as sensa\u00e7\u00f5es f\u00edsicas que suas emo\u00e7\u00f5es mais intensam provocam?<\/li>\n<\/ul>\n<h3>Aprimorando a comunica\u00e7\u00e3o verbal e n\u00e3o-verbal<\/h3>\n<p>A comunica\u00e7\u00e3o assertiva \u00e9 fundamental na constru\u00e7\u00e3o da intelig\u00eancia emocional. \u00c9 ela que favorece as rela\u00e7\u00f5es interpessoais e ajuda a resolver conflitos e situa\u00e7\u00f5es estressantes envolvendo pessoas.<\/p>\n<p>Para identificar os pontos de melhoria do coachee, quanto \u00e0 sua comunica\u00e7\u00e3o verbal e n\u00e3o-verbal, \u00e9 essencial investigar os seguintes pontos:<\/p>\n<ul>\n<li>Como voc\u00ea se comunica em situa\u00e7\u00f5es de raiva ou provoca\u00e7\u00e3o?<\/li>\n<li>Quais s\u00e3o as suas habilidades de comunica\u00e7\u00e3o?<\/li>\n<li>Como voc\u00ea se expressa ao gesticular?<\/li>\n<li>Qual \u00e9 a impress\u00e3o que voc\u00ea passa para as outras pessoas ao falar com elas?<\/li>\n<li>Voc\u00ea faz contato visual enquanto fala?<\/li>\n<li>Voc\u00ea consegue compreender as mudan\u00e7as de estado emocional nos outros enquanto se comunica?<\/li>\n<li>Voc\u00ea sabe manter um tom de voz amig\u00e1vel em suas conversas?<\/li>\n<li>O que voc\u00ea gostaria de melhorar na sua comunica\u00e7\u00e3o?<\/li>\n<\/ul>\n<h3>Resolvendo conflitos<\/h3>\n<p>Conflitos e desentendimentos s\u00e3o frequentes em diversos ambientes. Mesmo que algumas pessoas possuam alto n\u00edvel de sinergia, a possibilidade de um conflito \u00e9 sempre consider\u00e1vel.<\/p>\n<p>Para aumentar a intelig\u00eancia emocional do coachee, \u00e9 fundamental que ele tenha fluidez de racioc\u00ednio durante situa\u00e7\u00f5es conflituosas e consiga encontrar solu\u00e7\u00f5es para resolver suas pend\u00eancias.<\/p>\n<p>Para isso, o coach pode discutir com o seu cliente as seguintes perguntas:<\/p>\n<ul>\n<li>Em quais situa\u00e7\u00f5es os conflitos mais acontecem na sua vida?<\/li>\n<li>Com quais pessoas voc\u00ea costuma entrar em conflito?<\/li>\n<li>O que voc\u00ea sente durante um atrito com algu\u00e9m importante?<\/li>\n<li>Voc\u00ea sente algum sentimento negativo depois de ouvir palavras desagrad\u00e1veis?<\/li>\n<li>Como voc\u00ea se sente depois de uma briga?<\/li>\n<li>Como costuma resolver seus conflitos?<\/li>\n<li>Voc\u00ea possui iniciativa para pedir perd\u00e3o ou propor solu\u00e7\u00f5es efetivas?<\/li>\n<li>Quais pontos da sua personalidade atrapalham nesses momentos conflituosos?<\/li>\n<li>Quais qualidades voc\u00ea poderia usar melhor para que seus desentendimentos fossem menos desgastantes?<\/li>\n<\/ul>\n<p>A intelig\u00eancia emocional \u00e9 composta por diversos aspectos e pode ir muito al\u00e9m dos exemplos mostrados nesse artigo. \u00c9 interessante fazer um trabalho aprofundado de autoconhecimento com o coachee para entender quais s\u00e3o as particularidades das suas emo\u00e7\u00f5es e como elas se relacionam com o seu estado desejado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para alcan\u00e7ar o sucesso em qualquer \u00e1rea da vida \u00e9 preciso desenvolver diversas habilidades como determina\u00e7\u00e3o, motiva\u00e7\u00e3o, resili\u00eancia, din\u00e2mica, comunica\u00e7\u00e3o assertiva e, claro, intelig\u00eancia emocional. Ser inteligente emocionalmente significa saber identificar, interpretar e gerenciar suas emo\u00e7\u00f5es de forma a reduzir o estresse, melhorar relacionamentos, estabelecer empatia e resolver problemas. Dispor dessas caracter\u00edsticas \u00e9 de grande&hellip; <a href=\"https:\/\/www.sistemizecoach.com\/blog\/como-aumentar-a-inteligencia-emocional-dos-coachees-com-coaching\/\" class=\"more-link\">Continue lendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":1009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,7],"tags":[12,6,5],"class_list":["post-1006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-para-coaches","category-dicas","tag-atendimento","tag-coaching","tag-dicas"],"_links":{"self":[{"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":3,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"predecessor-version":[{"id":1010,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/posts\/1006\/revisions\/1010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/media\/1009"}],"wp:attachment":[{"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sistemizecoach.com\/blog\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}